{"id":14,"date":"2022-05-10T10:23:53","date_gmt":"2022-05-10T10:23:53","guid":{"rendered":"https:\/\/www.ghostwebdesign.co.uk\/?page_id=14"},"modified":"2026-01-05T19:48:20","modified_gmt":"2026-01-05T19:48:20","slug":"ghost-web-design-swindon-wiltshire-portfolio","status":"publish","type":"page","link":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/","title":{"rendered":"Website Portfolio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"14\" class=\"elementor elementor-14\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ae0413 elementor-section-full_width elementor-section-content-top elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"0ae0413\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0f8ddc\" data-id=\"f0f8ddc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-570a7f1 elementor-widget elementor-widget-text-editor\" data-id=\"570a7f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><strong>Chippenham Website Designer | Portfolio | Wiltshire<\/strong><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f1ac13 elementor-widget elementor-widget-text-editor\" data-id=\"3f1ac13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Web Design Portfolio<\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59f4d02 elementor-widget elementor-widget-text-editor\" data-id=\"59f4d02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chippenham Web Designer and SEO is a full-service digital agency based in Wiltshire Swindon, offering a comprehensive range of web design and search engine optimisation (SEO) services. Our portfolio showcases our expertise in creating visually appealing and user-friendly websites, optimised for search engines to drive traffic and improve visibility to targeted areas.<\/p>\n<p>Our skilled designers and developers work closely with clients to understand their unique business requirements and objectives. We use a combination of innovative design concepts, cutting-edge technology, and strategic planning to deliver custom websites that not only look great, but also provide a seamless user experience. Our websites are optimised for both desktop and mobile devices, ensuring that your brand is accessible to a wider audience.<\/p>\n<p>We often work with startups, helping them to establish a strong online presence by delivering fast loading websites that rank high in key marketed areas bespoke to the client.<\/p>\n<p>Overall, our portfolio of work showcases their ability to create visually stunning designs that are highly functional and effective. Their designs are clean, modern, and minimalist, with a focus on user experience and brand identity. Ghost&#8217;s portfolio is a testament to their commitment to delivering high-quality work that meets their clients&#8217; needs and exceeds their expectations.<\/p>\n<p>Feel free to take a moment to browse through a selection of our previous web design work, all designs are bespoke and designed in house.<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c9716b elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3c9716b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f165029\" data-id=\"f165029\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-743ea7a elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"743ea7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"540\" height=\"843\" src=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/07\/cirencester-aerials-preview-ghost-web-design-swindon-icon.co_.uk_.jpg?fit=540%2C843&amp;ssl=1\" class=\"attachment-large size-large wp-image-768\" alt=\"Chippenham Web Design Mobile Website Example\" srcset=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/07\/cirencester-aerials-preview-ghost-web-design-swindon-icon.co_.uk_.jpg?w=540&amp;ssl=1 540w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/07\/cirencester-aerials-preview-ghost-web-design-swindon-icon.co_.uk_.jpg?resize=192%2C300&amp;ssl=1 192w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-638f393 elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"638f393\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"769\" height=\"1024\" src=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/portfolio-2-ghost-web-design-swindon.jpg?fit=769%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-630\" alt=\"Chippenham Web Designer\" srcset=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/portfolio-2-ghost-web-design-swindon.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/portfolio-2-ghost-web-design-swindon.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/portfolio-2-ghost-web-design-swindon.jpg?resize=769%2C1024&amp;ssl=1 769w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/portfolio-2-ghost-web-design-swindon.jpg?resize=768%2C1022&amp;ssl=1 768w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/portfolio-2-ghost-web-design-swindon.jpg?resize=600%2C799&amp;ssl=1 600w\" sizes=\"(max-width: 769px) 100vw, 769px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-85f2ba9\" data-id=\"85f2ba9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50bd454 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"50bd454\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"284\" height=\"736\" src=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/example-2-ghost-web-design-swindon.jpg?fit=284%2C736&amp;ssl=1\" class=\"attachment-large size-large wp-image-106\" alt=\"Chippenham Web Design Example\" srcset=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/example-2-ghost-web-design-swindon.jpg?w=284&amp;ssl=1 284w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/example-2-ghost-web-design-swindon.jpg?resize=116%2C300&amp;ssl=1 116w\" sizes=\"(max-width: 284px) 100vw, 284px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-297a59e elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"297a59e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"312\" src=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/web-design-example-ghost-web-design-swindon.jpg?fit=284%2C312&amp;ssl=1\" class=\"attachment-large size-large wp-image-109\" alt=\"Chippenham Web Design Example\" srcset=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/web-design-example-ghost-web-design-swindon.jpg?w=284&amp;ssl=1 284w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/web-design-example-ghost-web-design-swindon.jpg?resize=273%2C300&amp;ssl=1 273w\" sizes=\"(max-width: 284px) 100vw, 284px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fd833f1\" data-id=\"fd833f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52defef elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"52defef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"432\" src=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/web-design-example-ghost-web-design-swindon-2.jpg?fit=284%2C432&amp;ssl=1\" class=\"attachment-large size-large wp-image-108\" alt=\"Chippenham Web Design Example\" srcset=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/web-design-example-ghost-web-design-swindon-2.jpg?w=284&amp;ssl=1 284w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/web-design-example-ghost-web-design-swindon-2.jpg?resize=197%2C300&amp;ssl=1 197w\" sizes=\"(max-width: 284px) 100vw, 284px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-894aca4 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"894aca4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"468\" src=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/example-ghost-web-design-swindon.jpg?fit=284%2C468&amp;ssl=1\" class=\"attachment-large size-large wp-image-107\" alt=\"Chippenham Web Design Example\" srcset=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/example-ghost-web-design-swindon.jpg?w=284&amp;ssl=1 284w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/example-ghost-web-design-swindon.jpg?resize=182%2C300&amp;ssl=1 182w\" sizes=\"(max-width: 284px) 100vw, 284px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7ec90a0\" data-id=\"7ec90a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-609b9d5 elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"609b9d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"656\" src=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/web-design-ghost-web-design-swindon-2.jpg?fit=284%2C656&amp;ssl=1\" class=\"attachment-large size-large wp-image-105\" alt=\"Chippenham Web Design Example\" srcset=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/web-design-ghost-web-design-swindon-2.jpg?w=284&amp;ssl=1 284w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/web-design-ghost-web-design-swindon-2.jpg?resize=130%2C300&amp;ssl=1 130w\" sizes=\"(max-width: 284px) 100vw, 284px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c46178 elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"6c46178\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"783\" height=\"1024\" src=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/portfolio-ghost-web-design-swindon.jpg?fit=783%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-631\" alt=\"Chippenham Web Designer\" srcset=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/portfolio-ghost-web-design-swindon.jpg?w=814&amp;ssl=1 814w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/portfolio-ghost-web-design-swindon.jpg?resize=229%2C300&amp;ssl=1 229w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/portfolio-ghost-web-design-swindon.jpg?resize=783%2C1024&amp;ssl=1 783w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/portfolio-ghost-web-design-swindon.jpg?resize=768%2C1005&amp;ssl=1 768w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/05\/portfolio-ghost-web-design-swindon.jpg?resize=600%2C785&amp;ssl=1 600w\" sizes=\"(max-width: 783px) 100vw, 783px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-caac939 elementor-section-full_width elementor-section-content-top elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"caac939\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-322e72e\" data-id=\"322e72e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1062299 elementor-widget elementor-widget-image\" data-id=\"1062299\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"718\" src=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2023\/03\/responsive-website-preview.jpg?fit=1024%2C718&amp;ssl=1\" class=\"attachment-large size-large wp-image-1489\" alt=\"responsive-website-preview\" srcset=\"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2023\/03\/responsive-website-preview.jpg?w=1232&amp;ssl=1 1232w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2023\/03\/responsive-website-preview.jpg?resize=300%2C210&amp;ssl=1 300w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2023\/03\/responsive-website-preview.jpg?resize=1024%2C718&amp;ssl=1 1024w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2023\/03\/responsive-website-preview.jpg?resize=768%2C539&amp;ssl=1 768w, https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2023\/03\/responsive-website-preview.jpg?resize=600%2C421&amp;ssl=1 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Chippenham Website Designer | Portfolio | Wiltshire Web Design Portfolio Chippenham Web Designer and SEO is a full-service digital agency based in Wiltshire Swindon, offering a comprehensive range of web design and search engine optimisation (SEO) services. Our portfolio showcases our expertise in creating visually appealing and user-friendly websites, optimised for search engines to drive [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chippenham Web Design - Portfolio Showcase<\/title>\n<meta name=\"description\" content=\"Explore our Chippenham Web Design - Portfolio for innovative and user-friendly web solutions crafted for your business.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chippenham Web Design - Portfolio Showcase\" \/>\n<meta property=\"og:description\" content=\"Explore our Chippenham Web Design - Portfolio for innovative and user-friendly web solutions crafted for your business.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/\" \/>\n<meta property=\"og:site_name\" content=\"Chippenham Web Design\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-05T19:48:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/07\/cirencester-aerials-preview-ghost-web-design-swindon-icon.co_.uk_.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/index.php\\\/ghost-web-design-swindon-wiltshire-portfolio\\\/\",\"url\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/index.php\\\/ghost-web-design-swindon-wiltshire-portfolio\\\/\",\"name\":\"Chippenham Web Design - Portfolio Showcase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/index.php\\\/ghost-web-design-swindon-wiltshire-portfolio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/index.php\\\/ghost-web-design-swindon-wiltshire-portfolio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cirencester-aerials-preview-ghost-web-design-swindon-icon.co_.uk_.jpg\",\"datePublished\":\"2022-05-10T10:23:53+00:00\",\"dateModified\":\"2026-01-05T19:48:20+00:00\",\"description\":\"Explore our Chippenham Web Design - Portfolio for innovative and user-friendly web solutions crafted for your business.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/index.php\\\/ghost-web-design-swindon-wiltshire-portfolio\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/index.php\\\/ghost-web-design-swindon-wiltshire-portfolio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/index.php\\\/ghost-web-design-swindon-wiltshire-portfolio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/chippenhamwebdesign.co.uk\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cirencester-aerials-preview-ghost-web-design-swindon-icon.co_.uk_.jpg?fit=540%2C843&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/chippenhamwebdesign.co.uk\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cirencester-aerials-preview-ghost-web-design-swindon-icon.co_.uk_.jpg?fit=540%2C843&ssl=1\",\"width\":540,\"height\":843,\"caption\":\"local web design example\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/index.php\\\/ghost-web-design-swindon-wiltshire-portfolio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Website Portfolio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/#website\",\"url\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/\",\"name\":\"Chippenham Web Design\",\"description\":\"Chippenham Web Design for Business\",\"publisher\":{\"@id\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/#organization\"},\"alternateName\":\"Chippenham Website Design\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/#organization\",\"name\":\"Chippenham Web Design\",\"alternateName\":\"Chippenham Website Design\",\"url\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-Chippenham-Web-Design-Logo.png\",\"contentUrl\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-Chippenham-Web-Design-Logo.png\",\"width\":1024,\"height\":1024,\"caption\":\"Chippenham Web Design\"},\"image\":{\"@id\":\"https:\\\/\\\/chippenhamwebdesign.co.uk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chippenham Web Design - Portfolio Showcase","description":"Explore our Chippenham Web Design - Portfolio for innovative and user-friendly web solutions crafted for your business.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/","og_locale":"en_GB","og_type":"article","og_title":"Chippenham Web Design - Portfolio Showcase","og_description":"Explore our Chippenham Web Design - Portfolio for innovative and user-friendly web solutions crafted for your business.","og_url":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/","og_site_name":"Chippenham Web Design","article_modified_time":"2026-01-05T19:48:20+00:00","og_image":[{"url":"https:\/\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/07\/cirencester-aerials-preview-ghost-web-design-swindon-icon.co_.uk_.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/","url":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/","name":"Chippenham Web Design - Portfolio Showcase","isPartOf":{"@id":"https:\/\/chippenhamwebdesign.co.uk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/#primaryimage"},"image":{"@id":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/#primaryimage"},"thumbnailUrl":"https:\/\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/07\/cirencester-aerials-preview-ghost-web-design-swindon-icon.co_.uk_.jpg","datePublished":"2022-05-10T10:23:53+00:00","dateModified":"2026-01-05T19:48:20+00:00","description":"Explore our Chippenham Web Design - Portfolio for innovative and user-friendly web solutions crafted for your business.","breadcrumb":{"@id":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/#primaryimage","url":"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/07\/cirencester-aerials-preview-ghost-web-design-swindon-icon.co_.uk_.jpg?fit=540%2C843&ssl=1","contentUrl":"https:\/\/i0.wp.com\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2022\/07\/cirencester-aerials-preview-ghost-web-design-swindon-icon.co_.uk_.jpg?fit=540%2C843&ssl=1","width":540,"height":843,"caption":"local web design example"},{"@type":"BreadcrumbList","@id":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/ghost-web-design-swindon-wiltshire-portfolio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chippenhamwebdesign.co.uk\/"},{"@type":"ListItem","position":2,"name":"Website Portfolio"}]},{"@type":"WebSite","@id":"https:\/\/chippenhamwebdesign.co.uk\/#website","url":"https:\/\/chippenhamwebdesign.co.uk\/","name":"Chippenham Web Design","description":"Chippenham Web Design for Business","publisher":{"@id":"https:\/\/chippenhamwebdesign.co.uk\/#organization"},"alternateName":"Chippenham Website Design","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chippenhamwebdesign.co.uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/chippenhamwebdesign.co.uk\/#organization","name":"Chippenham Web Design","alternateName":"Chippenham Website Design","url":"https:\/\/chippenhamwebdesign.co.uk\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/chippenhamwebdesign.co.uk\/#\/schema\/logo\/image\/","url":"https:\/\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2026\/01\/cropped-Chippenham-Web-Design-Logo.png","contentUrl":"https:\/\/chippenhamwebdesign.co.uk\/wp-content\/uploads\/2026\/01\/cropped-Chippenham-Web-Design-Logo.png","width":1024,"height":1024,"caption":"Chippenham Web Design"},"image":{"@id":"https:\/\/chippenhamwebdesign.co.uk\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":98,"href":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":2332,"href":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/14\/revisions\/2332"}],"wp:attachment":[{"href":"https:\/\/chippenhamwebdesign.co.uk\/index.php\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}